{"id":9900,"date":"2025-12-18T10:34:36","date_gmt":"2025-12-18T09:34:36","guid":{"rendered":"https:\/\/erik-marquardt.eu\/?p=9900"},"modified":"2025-12-18T10:35:52","modified_gmt":"2025-12-18T09:35:52","slug":"syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen","status":"publish","type":"post","link":"https:\/\/erik-marquardt.eu\/en\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/","title":{"rendered":"Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Rund ein Jahr nach dem Sturz des Assad-Regimes ist Syrien weiterhin von Gewalt, Straflosigkeit und politischer Willk\u00fcr gepr\u00e4gt. Inszenierte Wahlen und Bilder vermeintlicher Normalit\u00e4t \u00e4ndern daran nichts. Dennoch w\u00e4chst in Europa der politische Druck, gefl\u00fcchtete Syrer*innen in ihr Heimatland abzuschieben. Dabei <a href=\"https:\/\/www.sueddeutsche.de\/politik\/syrien-abschiebungen-unhcr-dobrindt-li.3322995\">warnen Expert*innen<\/a> wie das UN-Fl\u00fcchtlingshilfswerk eindringlich, dass Syrien viel zu instabil ist, um R\u00fcckkehrer*innen zu sch\u00fctzen oder angemessen versorgen zu k\u00f6nnen. Niemand kann aktuell verl\u00e4sslich einsch\u00e4tzen, ob das Land einen Weg in eine stabile Zukunft findet oder erneut in Gewalt versinkt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Machtvakuum, Straflosigkeit und neue Gewalt<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nach dem Sturz des Assad-Regimes im Dezember 2024 \u00fcbernahm die islamistische Miliz HTS die Kontrolle \u00fcber Damaskus und beansprucht seither die politische F\u00fchrung des Landes. Die Verbrechen der Assad-\u00c4ra wurden bislang nicht aufgearbeitet; mutma\u00dfliche T\u00e4ter teilweise sogar freigesprochen. Dieses Klima der Straflosigkeit l\u00e4sst die Menschen im Land schutzlos zur\u00fcck. Selbstjustiz, politisch motivierte T\u00f6tungen und ein tiefes Misstrauen gegen\u00fcber staatlichen Institutionen pr\u00e4gen den Alltag vieler Menschen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So kam es im M\u00e4rz beispielsweise in den <a href=\"https:\/\/www.amnesty.de\/aktuell\/syrien-massaker-alawiten-kriegsverbrechen\">K\u00fcstenregionen<\/a> im M\u00e4rz zu Massakern an Angeh\u00f6rigen religi\u00f6ser Minderheiten wie Alawit*innen und Christ*innen, begleitet von Pl\u00fcnderungen und Entf\u00fchrungen. Es herrscht eine <a href=\"https:\/\/www.vaticannews.va\/de\/welt\/news\/2025-03\/syrien-patriarch-johannes-x-massaker-christen-al-sharaa.html\">Atmosph\u00e4re der Angst<\/a>, in der selbst grundlegende Religionsfreiheit abgeschafft wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Selbstmordanschlag auf die <a href=\"https:\/\/www.tagesschau.de\/ausland\/asien\/syrien-anschlag-112.html\">Mar-Elias-Kirche in Damaskus<\/a> im Juni 2025, bei dem 25 Menschen get\u00f6tet und Dutzende verletzt wurden, zeigt, dass selbst zentrale religi\u00f6se Orte nicht gesch\u00fctzt sind. F\u00fcr die Bev\u00f6lkerung bedeutet dies, dass R\u00e4ume der Zuflucht und Gemeinschaft zu Orten der Unsicherheit geworden sind.<br>Besonders dramatisch war auch <a href=\"https:\/\/www.medico.de\/blog\/ist-das-neue-syrien-gescheitert-20167\">die Eskalation der Gewalt in der Provinz as-Sweida<\/a> im Juli. Beduinische Milizen und Regierungstruppen griffen die Provinz an und lieferten sich schwere K\u00e4mpfe mit lokalen drusischen Milizen. Dabei wurden \u00fcber 1.400 Menschen get\u00f6tet, darunter zahlreiche Zivilist*innen, und mehr als 150.000 Menschen vertrieben. <a href=\"https:\/\/www.bbc.com\/news\/articles\/cly84jn000do\">BBC-Recherchen<\/a> dokumentieren zudem schwere Kriegsverbrechen: Demnach sollen Regierungssoldaten Patient*innen in einem Krankenhaus in ihren Betten erschossen haben sollen. Diese Ereignisse zeigen klar, dass die syrischen Machthaber weder Schutz bieten noch Kontrolle \u00fcber wesentliche Sicherheitsbereiche besitzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Zerm\u00fcrbte Abkommen und verlorenes Vertrauen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Auch im kurdisch gepr\u00e4gten Nordosten Syrien bleibt die Lage instabil. <a href=\"https:\/\/apnews.com\/article\/syria-kurds-sdf-mazloum-abdi-army-merger-alsharaa-8de0ee121b7a475fbbc27cbe46784f32\">Die Spannungen<\/a> zwischen den Syrian Democratic Forces (SDF), einer kurdisch gef\u00fchrten Miliz, und der HTS rei\u00dfen nicht ab. Ein am 10. M\u00e4rz 2025 geschlossenes Abkommen sollte zur Stabilisierung der Region beitragen, blieb jedoch weitgehend wirkungslos. Das Scheitern l\u00e4sst sich vor allem durch die tiefe Verunsicherung in der Bev\u00f6lkerung erkl\u00e4ren: Die brutalen Angriffe in den K\u00fcstenregionen und das Massaker in as-Sweida haben die Menschen im Nordosten in Angst versetzt. Viele f\u00fcrchten, dass sich die Gewalt jederzeit auf ihre Region ausweiten k\u00f6nnte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zwar setzt sich die SDF f\u00fcr ein dezentrales Syrien ein, in dem Macht und Verantwortung zwischen Regionen und Zentralregierung geteilt werden, doch die F\u00fchrung in Damaskus blockiert dieses Modell. Sie betrachtet Dezentralisierung als Vorstufe eines schleichenden Zerfalls des Landes. Entsprechend steht auch ein <a href=\"https:\/\/adoptrevolution.org\/dezentralisierung-in-syrien\">weiteres Abkommen,<\/a> das nach erneuten Spannungen in Aleppo im Oktober ausgehandelt wurde, unter schlechten Vorzeichen. Ob es eingehalten wird, erscheint angesichts des tiefgreifenden Vertrauensverlusts derzeit v\u00f6llig offen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Scheinwahl statt politischem Aufbruch<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/fpc.org.uk\/op-ed-the-first-election-in-the-new-syria-a-missed-opportunity\/\">Die Parlamentswahl<\/a> vom 5. Oktober 2025 sollte ein Symbol f\u00fcr einen politischen Neuanfang sein. Stattdessen hat sie deutlich gemacht, wie fest \u00dcbergangspr\u00e4sident Ahmed al-Sharaa die Macht an sich gerissen hat. Die Wahl war weder frei noch fair, denn al-Sharaa hat sowohl das Wahlverfahren als auch dessen Ergebnis kontrolliert: Nach Dekret Nr. 143\/2025 ernennt er ein Drittel der Abgeordneten selbst und bestimmt die Mitglieder der Hohen Wahlkommission. Diese wiederum \u00fcberwacht nicht nur den gesamten Wahlprozess, sondern best\u00e4tigt auch die Vergabe der \u00fcbrigen Mandate; ein System geschlossener Kontrolle ohne unabh\u00e4ngige Instanzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hinzu kommen bewusst vage formulierte Ausschlusskriterien, die den willk\u00fcrlichen Ausschluss unerw\u00fcnschter Kandidat*innen erm\u00f6glichen. Unter Vorw\u00fcrfen wie angeblicher Unterst\u00fctzung des fr\u00fcheren Regimes oder Spaltung des Landes werden politische Konkurrenten ausgeschaltet. Betroffene erhalten weder Einblick in die Vorw\u00fcrfe noch die M\u00f6glichkeit, rechtlich dagegen vorzugehen. Auch von gesellschaftlicher Repr\u00e4sentation kann kaum die Rede sein: Die Frauenquote von 20 Prozent bleibt symbolisch, w\u00e4hrend marginalisierte Gruppen faktisch keine Stimme haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Syrien wurde kein politischer Neubeginn eingeleitet, sondern bestehende autorit\u00e4re Machtstrukturen lediglich unter neuem Namen fortgef\u00fchrt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Folgen f\u00fcr Europa: Politischer Druck statt Schutz<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Trotz der katastrophalen Lage im Land fordern Konservative und Rechtsextreme in Europa zunehmend Abschiebungen nach Syrien. \u00d6sterreich hat bereits erste Menschen nach Syrien abgeschoben. In Deutschland wird die Debatte vor allem <a href=\"https:\/\/www.tagesschau.de\/inland\/abschiebungen-syrien-merz-100.html\">vom Bundeskanzler befeuert<\/a>, der sogar den syrischen \u00dcbergangspr\u00e4sidenten nach Berlin eingeladen hat \u2013 eine Person, die noch bis vor kurzem als Terrorist eingestuft wurde. Die Signalwirkung dieser politischen Aufwertung ist deutlich: Sie sendet ein fatales Zeichen der Normalisierung an autorit\u00e4re und extremistische Akteure.Lediglich der Au\u00dfenminister widerspricht der populistischen R\u00fcckkehrdebatte deutlich: Nach seiner Syrienreise beschrieb er die Zerst\u00f6rung als \u201e<a href=\"https:\/\/www.zeit.de\/politik\/deutschland\/2025-11\/johann-wadephul-syrien-migranten-rueckkehr\">schlimmer als Deutschland 1945<\/a>\u201c.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Keine pauschale Asyl-Aussetzung: Karlsruhe stellt BAMF klar in die Schranken<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nach dem Sturz Assads setzte das Bundesamt f\u00fcr Migration und Fl\u00fcchtlinge (BAMF), wie auch mehrere andere EU-Staaten, <a href=\"https:\/\/de.euronews.com\/my-europe\/2024\/12\/09\/bundesamt-fur-migration-stoppt-bearbeitung-von-asylantragen-von-syrern?\">Asylverfahren f\u00fcr Syrer*innen<\/a> zun\u00e4chst pauschal aus. Begr\u00fcndet wurde das mit einem angeblichen Bedarf an weiterer \u201eAufkl\u00e4rung\u201c. <a href=\"https:\/\/rsw.beck.de\/aktuell\/daily\/meldung\/detail\/vg-karlsruhe-a8k568224-bamf-syrien-asylantraege-ungewisse-lage?\">Das Bundesverfassungsgericht hat jedoch klargestellt<\/a>, dass eine solche pauschale Aussetzung rechtswidrig ist. Die Lage in Syrien sei hinreichend bekannt, um Einzelf\u00e4lle zu pr\u00fcfen. Damit bleibt die rechtsstaatliche Verpflichtung zur Einzelfallpr\u00fcfung verbindlich und nicht verhandelbar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Praxis agieren die Beh\u00f6rden dennoch teils z\u00f6gerlich. F\u00fcr Betroffene bedeutet das anhaltende Unsicherheit; gerade f\u00fcr jene, die seit Jahren in Deutschland leben, arbeiten und gesellschaftlich integriert sind. Anstelle von Schutz und rechtlicher Klarheit dominiert damit weiterhin politische Abschreckung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Das Paradox der Abschiebungsdebatte: Fachkr\u00e4ftemangel vs. Schutzentzug<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Deutschland wirbt aktiv um Fach- und Arbeitskr\u00e4fte, gleichzeitig m\u00fcssen viele erwerbst\u00e4tige Syrer*innen um den Verlust ihres Schutzstatus f\u00fcrchten. Wird dieser entzogen, verlieren Betroffene in der Regel automatisch ihre Arbeitserlaubnis. Damit geraten nicht nur jahrelange Integrationsbem\u00fchungen ins Wanken, sondern auch die Existenzgrundlage der Betriebe, die auf ihre eingearbeiteten Mitarbeiter*innen angewiesen sind.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Abschiebepolitik, die \u00fcber den Entzug von Schutz funktioniert, steht damit neben menschlichen Werten auch in einem starken Widerspruch zu den eigenen arbeitsmarktpolitischen Zielen. Was als migrationspolitische H\u00e4rte verkauft wird, erweist sich damit auch \u00f6konomisch als kurzsichtig.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Es braucht Schutz statt Symbolpolitik<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Angesichts der anhaltenden Gewalt, Straflosigkeit, politischen Willk\u00fcr und der fragilen Sicherheitslage sind Abschiebungen nach Syrien politisch, humanit\u00e4r und rechtlich unverantwortlich. Eine verantwortungsvolle deutsche und europ\u00e4ische Politik muss deshalb den Schutz von Gefl\u00fcchteten in den Mittelpunkt stellen, rechtsstaatliche Verfahren konsequent st\u00e4rken und gleichzeitig gezielten Druck auf die neuen Machthaber in Syrien aus\u00fcben, um demokratische Ver\u00e4nderungen einzufordern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au\u00dferdem m\u00fcssen die Hauptaufnahmel\u00e4nder T\u00fcrkei, Libanon und Jordanien nachhaltig unterst\u00fctzt werden. Nur durch eine Verbindung von Schutz, Rechtsstaatlichkeit und internationaler Verantwortung kann langfristig ein Umfeld entstehen, in dem eine sichere und freiwillige R\u00fcckkehr \u00fcberhaupt denkbar ist.<\/p>","protected":false},"excerpt":{"rendered":"<p>Rund ein Jahr nach dem Sturz des Assad-Regimes ist Syrien weiterhin von Gewalt, Straflosigkeit und politischer Willk\u00fcr gepr\u00e4gt. Inszenierte Wahlen und Bilder vermeintlicher Normalit\u00e4t \u00e4ndern daran nichts. Dennoch w\u00e4chst in Europa der politische Druck, gefl\u00fcchtete Syrer*innen in ihr Heimatland abzuschieben. Dabei warnen Expert*innen wie das UN-Fl\u00fcchtlingshilfswerk eindringlich, dass Syrien viel zu instabil ist, um R\u00fcckkehrer*innen &hellip;<\/p>","protected":false},"author":2,"featured_media":9902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3,4],"tags":[],"class_list":["post-9900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","category-misc","with-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen - Erik Marquardt<\/title>\n<meta name=\"description\" content=\"Obwohl Syrien nach wie vor von Gewalt, Straflosigkeit und autorit\u00e4ren Kr\u00e4ften dominiert wird, fordern europ\u00e4ische Politiker immer lauter Abschiebungen dorthin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/erik-marquardt.eu\/en\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen - Erik Marquardt\" \/>\n<meta property=\"og:description\" content=\"Obwohl Syrien nach wie vor von Gewalt, Straflosigkeit und autorit\u00e4ren Kr\u00e4ften dominiert wird, fordern europ\u00e4ische Politiker immer lauter Abschiebungen dorthin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/erik-marquardt.eu\/en\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Erik Marquardt\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T09:34:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T09:35:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erik Marquardt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erik Marquardt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/\"},\"author\":{\"name\":\"Erik Marquardt\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\"},\"headline\":\"Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen\",\"datePublished\":\"2025-12-18T09:34:36+00:00\",\"dateModified\":\"2025-12-18T09:35:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/\"},\"wordCount\":1181,\"publisher\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\"},\"image\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg\",\"articleSection\":[\"Politik\",\"Vermischtes\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/\",\"name\":\"Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen - Erik Marquardt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg\",\"datePublished\":\"2025-12-18T09:34:36+00:00\",\"dateModified\":\"2025-12-18T09:35:52+00:00\",\"description\":\"Obwohl Syrien nach wie vor von Gewalt, Straflosigkeit und autorit\u00e4ren Kr\u00e4ften dominiert wird, fordern europ\u00e4ische Politiker immer lauter Abschiebungen dorthin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Foto via Unsplash.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/erik-marquardt.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#website\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/\",\"name\":\"Erik Marquardt\",\"description\":\"Mitglied des Europ\u00e4ischen Parlaments \",\"publisher\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/erik-marquardt.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\",\"name\":\"Erik Marquardt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\",\"contentUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\",\"width\":370,\"height\":123,\"caption\":\"Erik Marquardt\"},\"logo\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen - Erik Marquardt","description":"Obwohl Syrien nach wie vor von Gewalt, Straflosigkeit und autorit\u00e4ren Kr\u00e4ften dominiert wird, fordern europ\u00e4ische Politiker immer lauter Abschiebungen dorthin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/erik-marquardt.eu\/en\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/","og_locale":"en_GB","og_type":"article","og_title":"Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen - Erik Marquardt","og_description":"Obwohl Syrien nach wie vor von Gewalt, Straflosigkeit und autorit\u00e4ren Kr\u00e4ften dominiert wird, fordern europ\u00e4ische Politiker immer lauter Abschiebungen dorthin.","og_url":"https:\/\/erik-marquardt.eu\/en\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/","og_site_name":"Erik Marquardt","article_published_time":"2025-12-18T09:34:36+00:00","article_modified_time":"2025-12-18T09:35:52+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg","type":"image\/jpeg"}],"author":"Erik Marquardt","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Erik Marquardt","Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/#article","isPartOf":{"@id":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/"},"author":{"name":"Erik Marquardt","@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23"},"headline":"Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen","datePublished":"2025-12-18T09:34:36+00:00","dateModified":"2025-12-18T09:35:52+00:00","mainEntityOfPage":{"@id":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/"},"wordCount":1181,"publisher":{"@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23"},"image":{"@id":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/#primaryimage"},"thumbnailUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg","articleSection":["Politik","Vermischtes"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/","url":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/","name":"Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen - Erik Marquardt","isPartOf":{"@id":"https:\/\/erik-marquardt.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/#primaryimage"},"image":{"@id":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/#primaryimage"},"thumbnailUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg","datePublished":"2025-12-18T09:34:36+00:00","dateModified":"2025-12-18T09:35:52+00:00","description":"Obwohl Syrien nach wie vor von Gewalt, Straflosigkeit und autorit\u00e4ren Kr\u00e4ften dominiert wird, fordern europ\u00e4ische Politiker immer lauter Abschiebungen dorthin.","breadcrumb":{"@id":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/#primaryimage","url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg","contentUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg","width":2560,"height":1707,"caption":"Foto via Unsplash."},{"@type":"BreadcrumbList","@id":"https:\/\/erik-marquardt.eu\/syrien-2025-kein-frieden-keine-gerechtigkeit-und-kein-ort-fuer-abschiebungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/erik-marquardt.eu\/"},{"@type":"ListItem","position":2,"name":"Syrien 2025: Kein Frieden, keine Gerechtigkeit und kein Ort f\u00fcr Abschiebungen"}]},{"@type":"WebSite","@id":"https:\/\/erik-marquardt.eu\/#website","url":"https:\/\/erik-marquardt.eu\/","name":"Erik Marquardt","description":"Member of the European Parliament","publisher":{"@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/erik-marquardt.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23","name":"Erik Marquardt","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg","url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg","contentUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg","width":370,"height":123,"caption":"Erik Marquardt"},"logo":{"@id":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg"}}]}},"featured_image_src":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash-600x400.jpg","featured_image_src_square":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash-600x600.jpg","author_info":{"display_name":"Erik Marquardt","author_link":"https:\/\/erik-marquardt.eu\/en\/author\/erik\/"},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/mahmoud-sulaiman-aO9nGw9Cbk0-unsplash.jpg","_links":{"self":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/posts\/9900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/comments?post=9900"}],"version-history":[{"count":1,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/posts\/9900\/revisions"}],"predecessor-version":[{"id":9904,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/posts\/9900\/revisions\/9904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/media\/9902"}],"wp:attachment":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/media?parent=9900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/categories?post=9900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/tags?post=9900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}