{"id":3735,"date":"2021-11-21T18:55:00","date_gmt":"2021-11-21T17:55:00","guid":{"rendered":"https:\/\/erik-marquardt.eu\/?p=3735"},"modified":"2022-08-10T19:02:24","modified_gmt":"2022-08-10T17:02:24","slug":"die-deutsche-schande-von-kabul","status":"publish","type":"post","link":"https:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/","title":{"rendered":"Leaves: &#8222;The German Shame of Kabul&#8220;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Dieser Text erschien in den Bl\u00e4ttern f\u00fcr deutsche und Internationale Politik (November 2021) und ihr findet ihn auch unter <a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul\">diesem Link. <\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nur einen Tag vor dem Fall Kabuls soll der damalige afghanische Pr\u00e4sident Ashraf Ghani gegen\u00fcber US-Au\u00dfenminister Antony Blinken erkl\u00e4rt haben, er werde \u201ebis in den Tod k\u00e4mpfen\u201c.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn1\">[1]<\/a> Doch als die Taliban am 15. August \u2013 und damit deutlich fr\u00fcher als erwartet \u2013 die Macht in der afghanischen Hauptstadt \u00fcbernahmen, ergriff Ghani die Flucht. Er konnte nach Tadschikistan fliegen und von dort aus in die Vereinigten Arabischen Emirate reisen, wo ihm schnell und unb\u00fcrokratisch politisches Asyl gew\u00e4hrt wurde. Ashraf Ghani geh\u00f6rt damit zu einer kleinen Schicht privilegierter Afghanen und Afghaninnen mit genug Geld und Verbindungen, um sich rasch in Sicherheit zu bringen. Die meisten Menschen in Afghanistan genie\u00dfen diese Privilegien jedoch nicht. Nach der Macht\u00fcbernahme der Taliban versuchten daher Tausende, auf den Kabuler Flughafen zu gelangen. Dort hofften sie, eine Evakuierungsmaschine zu erreichen, die sie au\u00dfer Landes fliegen w\u00fcrde. Ihre Angst vor den neuen Machthabern war so gro\u00df, dass sich Menschen sogar an startende Flugzeuge klammerten. Einige von ihnen st\u00fcrzten bei diesem verzweifelten Fluchtversuch in den Tod.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In jenen Tagen verwandelte sich der Flughafen von Kabul in einen Ort der Hoffnung und des Schreckens: W\u00e4hrend zehntausende Menschen gerade noch evakuiert werden konnten \u2013 vor allem in die USA \u2013, verloren am 26. August 180 Menschen bei einem Bombenanschlag der Terrormiliz \u201eIslamischer Staat\u201c ihr Leben. Als Mitte August deutlich wurde, dass Afghanistan bald komplett an die Taliban fallen w\u00fcrde, entschied ich mich mit einigen anderen, nicht einfach tatenlos zuzusehen. Ich habe Afghanistan im Jahr 2016 als Fotograf besucht und dort viele Menschen kennengelernt, von denen einige nun gef\u00e4hrdet sind. Als Abgeordneter des Europ\u00e4ischen Parlaments bin ich zwar Teil der Delegation f\u00fcr die Beziehungen zu Afghanistan und arbeite auch in meinen Aussch\u00fcssen an Themen, die einen Bezug zum Land haben, aber in dieser Rolle kann man nicht direkt bei der Evakuierung von Menschen helfen. Daher haben wir einen zivilgesellschaftlichen Weg gew\u00e4hlt: Gemeinsam mit Mitstreiterinnen und Mitstreitern aus der Seenotrettung und dem Journalismus gr\u00fcndeten wir die \u201eKabul Luftbr\u00fccke\u201c und arbeiten seither daran, Menschen aus Afghanistan zu evakuieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schon bei einer ersten Rettungsaktion in der Nacht vom 25. auf den 26. August mit einem gecharterten Flugzeug konnten wir 18 Menschen vom Flughafen Kabul retten \u2013 und das, obwohl Teile des Ausw\u00e4rtigen Amts den Erfolg unserer Mission verhindern wollten. Zwischenzeitlich sollten die 18 afghanischen Ortskr\u00e4fte der Portugiesen wieder das Flugzeug verlassen \u2013 auf deutsche Anweisung. Der verantwortliche Mitarbeiter des Ausw\u00e4rtigen Amtes in Kabul stand direkt auf dem Flughafen neben der Crew, aber weigerte sich mit ihnen zu reden. Nach einem stundenlangen Thriller gelang es uns, die schutzsuchenden Menschen doch noch auszufliegen.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn2\">[2]<\/a> Eine nachvollziehbare Begr\u00fcndung des Ausw\u00e4rtigen Amts f\u00fcr die Behinderung unserer Mission, haben wir bis zum heutigen Tag nicht erhalten.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\"> Dieser Artikel stammt aus der Ausgabe November 2021. Klicken Sie hier, um zur Inhalts\u00fcbersicht dieser Ausgabe zu gelangen.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nachdem die Bundesregierung am 26. August die Evakuierung in Kabul abgebrochen hatte, konnten wir weitere 189 Menschen in den Flughafen und von dort aus in Sicherheit bringen.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn3\">[3]<\/a> Seither haben wir es immer wieder geschafft, Schutzsuchende, aber auch deutsche Staatsb\u00fcrgerinnen und -b\u00fcrger aus dem Land zu evakuieren, inzwischen sind es mehr als 400 Personen.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn4\">[4]<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Verschleppte Verfahren<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei der \u201eKabul Luftbr\u00fccke\u201c erleben wir t\u00e4glich, wie die Rettung von Menschen verhindert wird, weil Verfahren aus b\u00fcrokratischen Gr\u00fcnden verschleppt werden oder niemand zust\u00e4ndig sein m\u00f6chte. Das hat fatale Folgen: Mehrere Menschen, die auf deutschen Evakuierungslisten stehen, wurden bereits von den Taliban hingerichtet.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn5\">[5]<\/a> Obwohl deutsche Stellen \u00f6ffentlich behauptet haben, dass alle diese Menschen ausgeflogen werden sollen, wurde ihre Rettung praktisch verhindert: Listen wurden nicht weitergeleitet, Busse konnten nicht bezahlt werden, Flugkapazit\u00e4ten wurden nicht ausgeweitet und die Abstimmung verschiedener Beh\u00f6rden lief so schlecht, dass wir in zahlreichen Gespr\u00e4chen Informationen von einem ins andere Ministerium tragen mussten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Statt funktionierende technische L\u00f6sungen zu suchen, haben dutzende Beamte wochenlang Daten von E-Mails in Exceltabellen kopiert, in denen am Ende wohl niemand mehr so richtig durchsieht. Und der Transport der erw\u00e4hnten 189 Personen, die wir in den Flughafen Kabul bringen wollten, war erst erfolgreich, als die Bundeswehr bereits abgezogen war.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Solche Evakuierungen mit der \u201eKabul Luftbr\u00fccke\u201c zeigen, dass die Bundesregierung mit dem entsprechenden politischen Willen viel mehr Menschen h\u00e4tte retten k\u00f6nnen. Doch stattdessen entschied sie sich, die Evakuierung abzubrechen. Wie diese Verschleppung durch deutsche Beh\u00f6rden funktioniert, zeigt sich auch an der Familienzusammenf\u00fchrung: 4000 Menschen aus Afghanistan stehen laut Recherchen des Magazins \u201ePanorama\u201d und nach Auskunft des Ausw\u00e4rtigen Amts seit bis zu zwei Jahren auf der Warteliste f\u00fcr einen Termin, um \u00fcberhaupt die ben\u00f6tigten Unterlagen einreichen zu k\u00f6nnen.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn6\">[6]<\/a> Aufgrund dieser Verz\u00f6gerungstaktik sind viele Menschen nun unter Taliban-Herrschaft geraten, obwohl sie das Recht auf eine Familienzusammenf\u00fchrung in Deutschland haben. Inzwischen landen auch regelrecht absurde F\u00e4lle in unseren Postf\u00e4chern: So bekam ein allein reisender 10j\u00e4hriger Junge im afghanischen Herat die Nachricht, dass er nun nach Deutschland evakuiert werden k\u00f6nnte. Er m\u00fcsse dazu allerdings zur deutschen Botschaft ins Nachbarland Pakistan gehen. Dass die Grenzen geschlossen sind und man dort nicht hinkommt, sagte ihm jedoch niemand.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">All dies l\u00e4sst sich nicht einfach mit dem pl\u00f6tzlichen Vormarsch der Taliban erkl\u00e4ren \u2013 auch wenn Bundesregierung und Ausw\u00e4rtiges Amt genau das behaupten. Demnach habe der Siegeszug der Islamisten sie v\u00f6llig \u00fcberrascht. Erst mit der Evakuierung der US-Botschaft am 15. August wollen die zust\u00e4ndigen Stellen bemerkt haben, dass auch sie jetzt schnell evakuieren m\u00fcssen, weil sie den besonders gesicherten Bereich der afghanischen Hauptstadt, die Green Zone, nicht ohne US-Unterst\u00fctzung halten konnten. Gegen diese Behauptung spricht allerdings ein Bericht des \u201eSpiegel\u201c, demzufolge die deutsche Botschafterin in den USA, Emily Haber, die Bundesregierung bereits neun Tage vor dem Einmarsch der Taliban in Kabul vor einem schnellen Fall der Hauptstadt gewarnt hatte. Die Botschafterin habe das Ausw\u00e4rtige Amt gebeten, umgehend Notfallpl\u00e4ne f\u00fcr die Botschaft in Afghanistan auszuarbeiten.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn7\">[7]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Ausw\u00e4rtige Amt war also informiert, unternahm aber tagelang nichts, um eine schnellere Evakuierung des Botschaftspersonals, von deutschen Staatsb\u00fcrgerinnen, afghanischen Ortskr\u00e4ften und anderen Menschen, die Anspruch auf Hilfe hatten, zu gew\u00e4hrleisten. Viele Menschen h\u00e4tten nach der Warnung der Botschafterin noch mit Charterfl\u00fcgen au\u00dfer Landes gebracht werden k\u00f6nnen. Doch nichts geschah.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die alleingelassenen Ortskr\u00e4fte<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dabei hat allerdings nicht nur das Au\u00dfenministerium versagt. Vielmehr spielten bei all diesen Entscheidungen auch innenpolitische Erw\u00e4gungen eine gro\u00dfe Rolle. Erhebliche Verantwortung lastet dabei auch auf den Schultern von Bundesinnenminister Horst Seehofer. Bereits im Juni hatte ihn die Innenministerkonferenz dazu aufgefordert, die rasche Aufnahme von Ortskr\u00e4ften in die Wege zu leiten. Doch wie interne Dokumente, die dem \u201eTagesspiegel\u201c vorliegen, belegen, hat Seehofer blockiert und mit b\u00fcrokratischen H\u00fcrden versucht, die Rettung von Menschen zu verz\u00f6gern.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn8\">[8]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Methode, die Zahl der zu evakuierenden Menschen aus Afghanistan m\u00f6glichst niedrig zu halten, bestand darin, die Definition der Ortskr\u00e4fte so eng zu fassen, dass nur noch sehr wenige Menschen darunterfallen. Laut Ausw\u00e4rtigen Amt umfasst der Begriff Ortskr\u00e4fte nun \u201eehemalige Besch\u00e4ftigte des Ausw\u00e4rtigen Amts (Botschaft Kabul und Generalkonsulat Mazar-i Scharif), der Bundeswehr, der Bundespolizei, oder Agenturen der Entwicklungszusammenarbeit, sofern das Besch\u00e4ftigungsverh\u00e4ltnis nicht bereits vor 2013 endete.\u201d<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn9\">[9]<\/a> Vor der Innenministerkonferenz im badischen Rust im Juni 2021 war die Definition sogar auf jene Menschen beschr\u00e4nkt, deren Vertr\u00e4ge nicht vor 2019 geendet hatten. Wenn die Taliban aber Menschen jagen, weil diese mit ihren Feinden kooperiert haben, dann ist es f\u00fcr sie kein Kriterium, zu welchem Zeitpunkt diese besch\u00e4ftigt waren. Die Taliban k\u00e4men nicht auf den Gedanken, einen Stichtag auf den 31. Dezember 2012 festzulegen und all jene zu verschonen, die davor f\u00fcr die Bundeswehr gearbeitet haben. Der Einsatz dauerte zwanzig Jahre, also sollten auch alle Menschen, die in diesem Zeitraum f\u00fcr die Deutschen gearbeitet haben, als Ortskr\u00e4fte anerkannt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr die Taliban ist es auch irrelevant, ob die Menschen direkt bei ihrem Feind angestellt waren oder ihre Dienstleistungen \u00fcber einen Drittanbieter zur Verf\u00fcgung stellten. Wie der \u201eSpiegel\u201c umfangreich recherchierte, wurden Mitarbeiterinnen und Mitarbeiter der Bundeswehr in Afghanistan jedoch systematisch in Subunternehmen gedr\u00e4ngt, damit sie sp\u00e4ter keine Aufnahme in Deutschland finden.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn10\">[10]<\/a> Sie wurden bewusst \u201eoutgesourct\u201c, damit der deutsche Staat nicht die Verantwortung f\u00fcr ihr Leben und ihre Sicherheit \u00fcbernehmen muss.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dass es den deutschen Beh\u00f6rden vor allem um die Begrenzung der Zahl der Evakuierungsberechtigten geht, und weniger um die Sicherheit der Ortskr\u00e4fte, zeigt sich auch an den vielen E-Mails, die mich seit dem Fall Kabuls erreichen. Hundertfach melden sich Menschen, die f\u00fcr die Bundeswehr gearbeitet haben, aber am Ortskr\u00e4fteverfahren scheitern. Unter ihnen finden sich auch die Fluglotsen aus Mazar-e-Sharif, die seit 2012 Vertr\u00e4ge mit der Bundeswehr hatten. Sie organisierten den Abzug der deutschen Soldatinnen und Soldaten mit. Aber als der letzte Flieger abhob, wurden sie einfach zur\u00fcckgelassen. Auch Bundeswehrsoldaten setzen sich mittlerweile daf\u00fcr ein, dass diese Menschen nach Deutschland evakuiert werden, doch da sie nur mit Werkvertr\u00e4gen besch\u00e4ftigt waren, werden ihre Antr\u00e4ge bislang abgelehnt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Doch die Bundesregierung hintertrieb nicht nur die Aufnahme von Menschen, sondern versuchte auch, so lange wie m\u00f6glich an ihrer Abschiebepraxis festzuhalten. Schon am 12. Juli hatte ich in meiner Funktion als Europaabgeordneter einen offenen Brief an Bundesau\u00dfenminister Heiko Maas gesandt, in dem ich darum bat, den Bericht des Ausw\u00e4rtigen Amtes \u00fcber die asyl- und abschiebungsrelevante Lage in Afghanistan an die neuen Erkenntnisse und Entwicklungen anzupassen.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn11\">[11]<\/a> Denn der Bericht bildete nicht die zu diesem Zeitpunkt aktuelle und sich bereits rapide verschlechternde Lage ab, sondern diente vor allem dazu, weiterhin Menschen aus Deutschland nach Afghanistan abschieben zu k\u00f6nnen. Dabei hatten die Taliban schon damals gro\u00dfe Teile des Landes unter ihre Kontrolle gebracht. L\u00e4ngst war absehbar, dass sie in naher Zukunft in Kabul einmarschieren w\u00fcrden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erst kurz zuvor war bekannt geworden, dass bereits am 21. Juni ein im Februar aus Deutschland abgeschobener Afghane durch eine Handgranate get\u00f6tet worden war.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn12\">[12]<\/a> Auch die damalige afghanische Regierung bat darum, die Abschiebungen aufgrund der Sicherheitslage vorerst auszusetzen.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn13\">[13]<\/a> Trotzdem f\u00fchrte die Bundesregierung weiterhin Sammelabschiebungen nach Afghanistan durch. Erst am 11. August, vier Tage vor dem Fall Kabuls, setzte das Bundesinnenministerium die Abschiebungen nach Afghanistan aus.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn14\">[14]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noch in der Vorwoche, am 5. August, hatte Seehofer gemeinsam mit den zust\u00e4ndigen Ministern aus \u00d6sterreich, D\u00e4nemark, Griechenland, Belgien und der Ministerin aus den Niederlanden in einem Brief an den Vizepr\u00e4sidenten der EU-Kommission, Margaritis Schinas, und die zust\u00e4ndige EU-Innenkommissarin Ylva Johansson gefordert, die Abschiebungen nach Afghanistan fortzuf\u00fchren<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn15\">[15]<\/a> \u2013 entgegen der Bitten der damaligen afghanischen Regierung. Doch die Ministerin und die Minister dr\u00e4ngten in ihrem Brief darauf, den Appell aus Kabul zu ignorieren. Dies zeigt, dass es ihnen nicht um die Rechte und die m\u00f6gliche Gef\u00e4hrdung von Menschen ging. Es ging ihnen auch nicht um einen n\u00fcchternen Blick auf die Realit\u00e4t in den Herkunftsl\u00e4ndern oder darum, dass Menschen bedroht sind, weil sie mit europ\u00e4ischen Truppen zusammengearbeitet haben. Nein, es ging und geht einzig und allein darum, Abschiebungen und eine restriktive Fl\u00fcchtlingspolitik zu rechtfertigen, auch wenn man dazu die Augen vor der Realit\u00e4t verschlie\u00dfen muss.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Lehren aus der deutschen Schande von Kabul<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei alledem spielte nicht zuletzt auch Wahltaktik eine Rolle: Kabul fiel nur gut einen Monat vor der Bundestagswahl am 26. September. Bereits am 23. Juni hatte die Bundestagsfraktion der Gr\u00fcnen einen Antrag zur Aufnahme afghanischer Ortskr\u00e4fte gestellt. Die Fraktionen von CDU\/CSU und SPD lehnten den Antrag jedoch gemeinsam mit der AfD ab.<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn16\">[16]<\/a> Es ist durchaus \u00fcblich, dass die Regierungsfraktionen Antr\u00e4ge der Opposition ablehnen. Dennoch steht es ihnen frei, eigene Antr\u00e4ge zum selben Thema einzubringen. Doch dies geschah in dem Fall nicht. Das Verhalten der Koalitionspartner erkl\u00e4rt sich auch daraus, dass sie kurz vor der Wahl keine gr\u00f6\u00dfere Anzahl von afghanischen Schutzberechtigten nach Deutschland kommen lassen wollten.<a href=\"https:\/\/www.blaetter.de\/sommer\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bereits an dem Tag, an dem Kabul an die Taliban fiel, twitterte der CDU-Abgeordnete und Obmann im Ausw\u00e4rtigen Ausschuss, Roderich Kiesewetter zwar: \u201eEs war ein gro\u00dfer und gravierender Fehler, den Antrag der Gr\u00fcnen \u2013 aus Prinzip \u2013 abzulehnen. Punkt.\u201c<a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftn17\">[17]<\/a> Doch in weiten Teilen von CDU\/CSU und SPD gab es einen breiten Konsens, Migration und Flucht aus dem Wahlkampf herauszuhalten, weil man bef\u00fcrchtete, dass diese Themen der rechtsradikalen AfD nutzen k\u00f6nnten. Da war die notwendige und schnelle Evakuierung von zehntausenden Menschen aus Afghanistan kein Thema, das man offensiv auf die Agenda setzen wollte. Doch diese Strategie ging nicht auf. Die Bilder vom Kabuler Flughafen bestimmten die Nachrichtensendungen kurz vor der Wahl. Und wer \u00fcber Jahre eine gro\u00dfe Herausforderung wie Flucht und Migration nicht bestm\u00f6glich managen will, sondern versucht, das Thema aus der politischen Debatte zu halten, wird weder den Menschen noch der Demokratie helfen. Der Erfolg der Rechtsradikalen h\u00e4ngt nicht damit zusammen, dass man Schutzsuchende aufnimmt, sondern erkl\u00e4rt sich daraus, dass die anderen Parteien an konkreten Herausforderungen scheitern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist besch\u00e4mend f\u00fcr die Bundesregierung, dass eine ad-hoc gegr\u00fcndete Initiative aus der Zivilgesellschaft wie die \u201eKabul Luftbr\u00fccke\u201c bereits zwei Wochen nach ihrer Gr\u00fcndung Menschen aus Kabul evakuieren konnte, w\u00e4hrend die Bundeswehr bereits abgezogen wurde. Umso mehr gilt jetzt: Die Evakuierungen aus Afghanistan m\u00fcssen fortgef\u00fchrt werden. Immer noch leben viele tausend Menschen in Afghanistan, die aufgrund ihrer Beziehungen oder ihrer Zusammenarbeit mit den Deutschen gef\u00e4hrdet sind. Wenn ihre Rettung an zu geringen personellen Kapazit\u00e4ten bei der Bundesregierung, den Ministerien und den zust\u00e4ndigen \u00c4mtern scheitert, m\u00fcssen diese aufgestockt werden, um dann konsequent und m\u00f6glichst z\u00fcgig gef\u00e4hrdete Personen zu evakuieren. Zugleich m\u00fcssen die Listen f\u00fcr Evakuierungsberechtigte wieder ge\u00f6ffnet werden. Und wir brauchen in Deutschland und der EU jeweils angemessene Aufnahmeprogramme, in deren Rahmen Menschen umgesiedelt werden k\u00f6nnen, damit sie sich nicht in die H\u00e4nde von Schleppern begeben und auf einen lebensgef\u00e4hrlichen Weg nach Europa machen m\u00fcssen. Die entsprechenden Verfahren m\u00fcssen erleichtert und entb\u00fcrokratisiert werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nat\u00fcrlich darf man nicht vergessen, dass die gro\u00dfen Herausforderungen f\u00fcr die afghanische Gesellschaft nicht durch die Flucht nach Europa gel\u00f6st werden. Doch Zehntausende, die sich Jahrzehnte f\u00fcr uns, f\u00fcr Menschen- und Frauenrechte eingesetzt haben, m\u00fcssen das Land nun verlassen k\u00f6nnen. Sie haben verdient, dass wir ihnen das erm\u00f6glichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir k\u00f6nnen die deutsche Schande von Kabul bei der Evakuierung nicht wiedergutmachen. Aber wir k\u00f6nnen zumindest zeigen, dass wir daraus gelernt haben und jetzt versuchen, es besser zu machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref1\"><sup>[1]<\/sup><\/a>&nbsp;Friederike B\u00f6ge, Ein Hubschrauber voller Geld, in: \u201eFrankfurter Allgemeine Zeitung\u201c, 24.8.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref2\"><sup>[2]<\/sup><\/a>&nbsp;Wolfgang Bauer, 170 Sitzpl\u00e4tze, 170 Leben, <a href=\"http:\/\/www.zeit.de\">www.zeit.de<\/a>, 28.8.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref3\"><sup>[3]<\/sup><\/a>&nbsp;Muriel Kalisch, \u201eLass uns ein Flugzeug mieten\u201d, <a href=\"http:\/\/www.spiegel.de\">www.spiegel.de<\/a>, 5.9.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref4\"><sup>[4]<\/sup><\/a>&nbsp;Christine Keck, \u201eWir holen jede Woche Afghanen raus\u201d, <a href=\"http:\/\/www.stuttgarter-zeitung.de\">www.stuttgarter-zeitung.de<\/a>, 8.10.2021; Private Initiative evakuiert elf Deutsche aus Kabul \u2013 neun von ihnen sind minderj\u00e4hrig, <a href=\"http:\/\/www.rnd.de\">www.rnd.de<\/a>, 6.10.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref5\"><sup>[5]<\/sup><\/a>&nbsp;Joana Rettig, Mindestens sechs Menschen auf deutschen Evakuierungslisten in Afghanistan hingerichtet, <a href=\"http:\/\/www.politik.watson.de\">www.politik.watson.de<\/a>, 9.9.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref6\"><sup>[6]<\/sup><\/a>&nbsp;Armin Ghassim und Jonas Schreij\u00e4g, Fl\u00fcchtlinge: Beh\u00f6rden verschleppen Familiennachzug, <a href=\"http:\/\/www.tagesschau.de\">www.tagesschau.de<\/a>, 30.9.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref7\"><sup>[7]<\/sup><\/a>&nbsp;Matthias Gebauer und Christoph Schult, Geheimer Kabelbericht warnte fr\u00fch vor Kollaps in Kabul, in: \u201eDer Spiegel\u201c, 6.9.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref8\"><sup>[8]<\/sup><\/a>&nbsp;Georg Ismar, Die Kabul-Krise der Regierung Merkel und das Bild, dass bleiben wird, <a href=\"http:\/\/www.tagesspiegel.de\">www.tagesspiegel.de<\/a>, 18.8.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref9\">[9]<\/a>&nbsp;<\/sup>Fragen und Antworten: Unterst\u00fctzung bei der Ausreise aus Afghanistan, <a href=\"http:\/\/www.auswaertiges-amt.de\/\">www.auswaertiges-amt.de<\/a>, 11.10.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref10\">[10]<\/a>&nbsp;<\/sup>Matthias Gebauer, Christoph Reuter und Fidelius Schmid, Wie systematisch die Bundeswehr das Outsourcing ihrer Ortskr\u00e4fte betrieb, <a href=\"http:\/\/www.spiegel.de\">www.spiegel.de<\/a>, 25.6.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref11\">[11]<\/a>&nbsp;<\/sup>Erik Marquardt, Offener Brief an Heiko Maas zu Abschiebungen nach Afghanistan, <a href=\"http:\/\/www.erik-marquardt.eu\/\">www.erik-marquardt.eu<\/a>, 15.7.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref12\"><sup>[12]<\/sup><\/a>&nbsp;Kaija Kutter, In den Tod geschickt, <a href=\"http:\/\/www.taz.de\">www.taz.de<\/a>, 6.7.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref13\"><sup>[13]<\/sup><\/a>&nbsp;Afghanistan fordert Abschiebestopp aus Europa, <a href=\"http:\/\/www.zeit.de\/\">www.zeit.de<\/a>, 10.7.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref14\">[14]<\/a>&nbsp;<\/sup>Seehofer: Abschiebungen zurzeit zu gef\u00e4hrlich, <a href=\"http:\/\/www.zdf.de\">www.zdf.de<\/a>, 11.8.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><sup><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref15\">[15]<\/a>&nbsp;<\/sup>Returns to Afghanistan \u2013 Letter to EU Commission, <a href=\"http:\/\/www.fragdenstaat.de\">www.fragdenstaat.de<\/a>, 5.8.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref16\"><sup>[16]<\/sup><\/a>&nbsp;Antrag zur Aufnahme afghanischer Ortskr\u00e4fte abgelehnt, <a href=\"http:\/\/www.bundestag.de\">www.bundestag.de<\/a>, 23.6.2021; Kersten Knipp, Kritik an hohen H\u00fcrden f\u00fcr Aufnahme afghanischer Ortskr\u00e4fte, <a href=\"http:\/\/www.dw.de\">www.dw.de<\/a>, 27.6.2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\/die-deutsche-schande-von-kabul#_ftnref17\"><sup>[17]<\/sup><\/a>&nbsp;www.<a href=\"https:\/\/twitter.com\/rkiesewetter\/status\/1426989480691605507?lang=de\">twitter.com\/rkiesewetter<\/a>, 15.8.2021. Themen: <a href=\"https:\/\/www.blaetter.de\/themen\/migration\">Migration<\/a>, <a href=\"https:\/\/www.blaetter.de\/themen\/krieg-und-frieden\">Krieg und Frieden<\/a>, <a href=\"https:\/\/www.blaetter.de\/themen\/menschenrechte\">Menschenrechte<\/a> Aus: <a href=\"https:\/\/www.blaetter.de\/ausgabe\/2021\/november\">\u00bbBl\u00e4tter\u00ab 11\/2021<\/a>, S. 77-82<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieser Text erschien in den Bl\u00e4ttern f\u00fcr deutsche und Internationale Politik (November 2021) und ihr findet ihn auch unter diesem Link. Nur einen Tag vor dem Fall Kabuls soll der damalige afghanische Pr\u00e4sident Ashraf Ghani gegen\u00fcber US-Au\u00dfenminister Antony Blinken erkl\u00e4rt haben, er werde \u201ebis in den Tod k\u00e4mpfen\u201c.[1] Doch als die Taliban am 15. August &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3737,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-3735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-presse","with-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bl\u00e4tter: &quot;Die deutsche Schande von Kabul&quot; - Erik Marquardt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die deutsche Schande von Kabul\" \/>\n<meta property=\"og:description\" content=\"Dieser Text erschien in den Bl\u00e4ttern f\u00fcr deutsche und Internationale Politik (November 2021) und ihr findet ihn auch unter diesem Link. Nur einen Tag vor dem Fall Kabuls soll der damalige afghanische Pr\u00e4sident Ashraf Ghani gegen\u00fcber US-Au\u00dfenminister Antony Blinken erkl\u00e4rt haben, er werde \u201ebis in den Tod k\u00e4mpfen\u201c.[1] Doch als die Taliban am 15. August &hellip;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/\" \/>\n<meta property=\"og:site_name\" content=\"Erik Marquardt\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-21T17:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-10T17:02:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1351\" \/>\n\t<meta property=\"og:image:height\" content=\"886\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erik Marquardt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Die deutsche Schande von Kabul\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erik Marquardt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/\"},\"author\":{\"name\":\"Erik Marquardt\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\"},\"headline\":\"Bl\u00e4tter: &#8222;Die deutsche Schande von Kabul&#8220;\",\"datePublished\":\"2021-11-21T17:55:00+00:00\",\"dateModified\":\"2022-08-10T17:02:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/\"},\"wordCount\":2699,\"publisher\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\"},\"image\":{\"@id\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Blaetter.jpg\",\"articleSection\":[\"Presse\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/\",\"url\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/\",\"name\":\"Bl\u00e4tter: \\\"Die deutsche Schande von Kabul\\\" - Erik Marquardt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Blaetter.jpg\",\"datePublished\":\"2021-11-21T17:55:00+00:00\",\"dateModified\":\"2022-08-10T17:02:24+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Blaetter.jpg\",\"contentUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Blaetter.jpg\",\"width\":1351,\"height\":886},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/erik-marquardt.eu\\\/en\\\/the-german-shame-of-kabul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/erik-marquardt.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bl\u00e4tter: &#8222;Die deutsche Schande von Kabul&#8220;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#website\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/\",\"name\":\"Erik Marquardt\",\"description\":\"Mitglied des Europ\u00e4ischen Parlaments \",\"publisher\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/erik-marquardt.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\",\"name\":\"Erik Marquardt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\",\"contentUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\",\"width\":370,\"height\":123,\"caption\":\"Erik Marquardt\"},\"logo\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leaves: \"The German Shame of Kabul\" - Erik Marquardt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/","og_locale":"en_GB","og_type":"article","og_title":"Die deutsche Schande von Kabul","og_description":"Dieser Text erschien in den Bl\u00e4ttern f\u00fcr deutsche und Internationale Politik (November 2021) und ihr findet ihn auch unter diesem Link. Nur einen Tag vor dem Fall Kabuls soll der damalige afghanische Pr\u00e4sident Ashraf Ghani gegen\u00fcber US-Au\u00dfenminister Antony Blinken erkl\u00e4rt haben, er werde \u201ebis in den Tod k\u00e4mpfen\u201c.[1] Doch als die Taliban am 15. August &hellip;","og_url":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/","og_site_name":"Erik Marquardt","article_published_time":"2021-11-21T17:55:00+00:00","article_modified_time":"2022-08-10T17:02:24+00:00","og_image":[{"width":1351,"height":886,"url":"http:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg","type":"image\/jpeg"}],"author":"Erik Marquardt","twitter_card":"summary_large_image","twitter_title":"Die deutsche Schande von Kabul","twitter_image":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg","twitter_misc":{"Written by":"Erik Marquardt","Estimated reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/#article","isPartOf":{"@id":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/"},"author":{"name":"Erik Marquardt","@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23"},"headline":"Bl\u00e4tter: &#8222;Die deutsche Schande von Kabul&#8220;","datePublished":"2021-11-21T17:55:00+00:00","dateModified":"2022-08-10T17:02:24+00:00","mainEntityOfPage":{"@id":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/"},"wordCount":2699,"publisher":{"@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23"},"image":{"@id":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/#primaryimage"},"thumbnailUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg","articleSection":["Presse"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/","url":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/","name":"Leaves: \"The German Shame of Kabul\" - Erik Marquardt","isPartOf":{"@id":"https:\/\/erik-marquardt.eu\/#website"},"primaryImageOfPage":{"@id":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/#primaryimage"},"image":{"@id":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/#primaryimage"},"thumbnailUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg","datePublished":"2021-11-21T17:55:00+00:00","dateModified":"2022-08-10T17:02:24+00:00","breadcrumb":{"@id":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/#primaryimage","url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg","contentUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg","width":1351,"height":886},{"@type":"BreadcrumbList","@id":"http:\/\/erik-marquardt.eu\/en\/the-german-shame-of-kabul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/erik-marquardt.eu\/"},{"@type":"ListItem","position":2,"name":"Bl\u00e4tter: &#8222;Die deutsche Schande von Kabul&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/erik-marquardt.eu\/#website","url":"https:\/\/erik-marquardt.eu\/","name":"Erik Marquardt","description":"Member of the European Parliament","publisher":{"@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/erik-marquardt.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23","name":"Erik Marquardt","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg","url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg","contentUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg","width":370,"height":123,"caption":"Erik Marquardt"},"logo":{"@id":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg"}}]}},"featured_image_src":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg","featured_image_src_square":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg","author_info":{"display_name":"Erik Marquardt","author_link":"https:\/\/erik-marquardt.eu\/en\/author\/erik\/"},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2022\/08\/Blaetter.jpg","_links":{"self":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/posts\/3735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/comments?post=3735"}],"version-history":[{"count":0,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/posts\/3735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/media\/3737"}],"wp:attachment":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/media?parent=3735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/categories?post=3735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/tags?post=3735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}