{"id":3205,"date":"2022-01-25T19:26:00","date_gmt":"2022-01-25T18:26:00","guid":{"rendered":"https:\/\/erik-marquardt.eu\/?p=3205"},"modified":"2022-01-26T19:42:57","modified_gmt":"2022-01-26T18:42:57","slug":"kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig","status":"publish","type":"post","link":"https:\/\/erik-marquardt.eu\/en\/commission-holds-greek-processing-of-asylum-seekers-for-europe-unlawful\/","title":{"rendered":"Commission considers Greek processing of asylum applications to be contrary to European law"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Griechenland lehnt Asylantr\u00e4ge mit der Begr\u00fcndung ab, die T\u00fcrkei sei ein &#8222;sicherer Drittstaat&#8220;, doch die T\u00fcrkei l\u00e4sst diese nicht einreisen. Aus einer Anfrage von mir geht nun hervor, dass die EU-Kommission dieses Vorgehen als europarechtswidrig einstuft. Obwohl die T\u00fcrkei seit M\u00e4rz 2020 keine R\u00fcck\u00fcbernahmen akzeptiert, lehnt Griechenland die Antr\u00e4ge syrischer, afghanischer, somalischer, pakistanischer und bangladeschischer Staatsangeh\u00f6riger auf der Grundlage ab, die T\u00fcrkei stelle f\u00fcr ebendiese einen \u201esicheren Drittstaat\u201c dar. Gleichzeitig hat die Kommission in ihrer Antwort auf die Anfrage zur schriftlichen Beantwortung P-000604\/2021 jedoch erneut darauf hingewiesen, dass es \u201ein Artikel 38 Absatz 4 der Asylverfahrensrichtlinie hei\u00dft [&#8230;]: \u201aErlaubt der Drittstaat dem Antragsteller nicht, in sein Hoheitsgebiet einzureisen, so m\u00fcssen die Mitgliedstaaten sicherstellen, dass Zugang zu einem [Asyl-] Verfahren gew\u00e4hrt wird\u2018. Im Einklang mit dieser Bestimmung k\u00f6nnen Antragsteller, deren Antrag f\u00fcr unzul\u00e4ssig erkl\u00e4rt wurde, daher erneut einen Antrag stellen.\u201c Die Kommission informiert in ihrer Antwort an mich auch dar\u00fcber, dass sie der griechischen Regierung bereits erkl\u00e4rt haben, &#8222;dass die bedingungslose Erhebung einer Geb\u00fchr von 100&nbsp;EUR f\u00fcr Folgeantr\u00e4ge hinsichtlich des effektiven Zugangs zum Asylverfahren problematisch ist.&#8220;  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die gesamte Anfrage mit Antworten in mehreren Sprachen findet ihr auch <a href=\"https:\/\/www.europarl.europa.eu\/doceo\/document\/E-9-2021-005103_DE.html\">hier.<\/a> <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Meine Anfrage<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Obwohl die T\u00fcrkei seit M\u00e4rz 2020 keine R\u00fcck\u00fcbernahmen akzeptiert, lehnt Griechenland die Antr\u00e4ge syrischer, afghanischer, somalischer, pakistanischer und bangladeschischer Staatsangeh\u00f6riger auf der Grundlage ab, die T\u00fcrkei stelle f\u00fcr ebendiese einen \u201esicheren Drittstaat\u201c dar. Gleichzeitig hat die Kommission in ihrer Antwort auf die Anfrage zur schriftlichen Beantwortung P-000604\/2021 jedoch erneut darauf hingewiesen, dass es \u201ein Artikel 38 Absatz 4 der Asylverfahrensrichtlinie hei\u00dft [&#8230;]: \u201aErlaubt der Drittstaat dem Antragsteller nicht, in sein Hoheitsgebiet einzureisen, so m\u00fcssen die Mitgliedstaaten sicherstellen, dass Zugang zu einem [Asyl-] Verfahren gew\u00e4hrt wird\u2018. Im Einklang mit dieser Bestimmung k\u00f6nnen Antragsteller, deren Antrag f\u00fcr unzul\u00e4ssig erkl\u00e4rt wurde, daher erneut einen Antrag stellen.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1.&nbsp;Wie viele Folgeantr\u00e4ge wurden von Personen gestellt, deren urspr\u00fcnglicher Asylantrag auf der Grundlage abgelehnt wurde, die T\u00fcrkei sei f\u00fcr sie ein sicherer Drittstaat?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2.&nbsp;In wie vielen dieser F\u00e4lle brachte Griechenland Artikel 38 Absatz 4 der Asylverfahrensrichtlinie zur Anwendung? Ist Artikel 23 des griechischen Gesetzes 4825\/2021, dem zufolge f\u00fcr die Einreichung eines zweiten Antrags eine Geb\u00fchr von 100 EUR entsteht, mit Artikel 38 Absatz 4 der Asylverfahrensrichtlinie vereinbar?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.&nbsp;Ist es mit Artikel 38 Absatz 4 der Asylverfahrensrichtlinie vereinbar, solche Folgeantr\u00e4ge mit der Begr\u00fcndung als unzul\u00e4ssig abzulehnen, der Antragsteller habe keine neuen Elemente in Bezug auf die T\u00fcrkei als sicheren Drittstaat geltend gemacht?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Antwort von Ylva Johansson im Namen der Europ\u00e4ischen Kommission am 25.1.2022<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">1. Die Kommissionsdienststellen leiteten die Frage des Herrn Abgeordneten zur Beantwortung an die nationalen Beh\u00f6rden weiter, die ihm die Antwort wird so bald wie m\u00f6glich \u00fcbermitteln werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Gem\u00e4\u00df Artikel&nbsp;38 Absatz&nbsp;4 der Asylverfahrensrichtlinie \u201em\u00fcssen die Mitgliedstaaten sicherstellen, dass im Einklang mit den Grunds\u00e4tzen und Garantien nach Kapitel&nbsp;II Zugang zu einem Verfahren gew\u00e4hrt wird\u201c. Obschon in Kapitel&nbsp;II der Asylverfahrensrichtlinie die Geb\u00fchrenfrage nicht geregelt ist, hat die Kommission die griechischen Beh\u00f6rden darauf hingewiesen, dass die bedingungslose Erhebung einer Geb\u00fchr von 100&nbsp;EUR f\u00fcr Folgeantr\u00e4ge hinsichtlich des effektiven Zugangs zum Asylverfahren problematisch ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Voraussetzung f\u00fcr die Anwendung des Artikels&nbsp;38 Absatz&nbsp;4 der Asylverfahrensrichtlinie ist, dass der Drittstaat dem Antragsteller die Einreise in sein Hoheitsgebiet nicht erlaubt. Ist diese Voraussetzung erf\u00fcllt, m\u00fcssen die Mitgliedstaaten sicherstellen, dass der Zugang zu einem Verfahren in der Sache gew\u00e4hrt wird. Sie d\u00fcrfen den Folgeantrag auf der Grundlage des Konzepts des sicheren Drittstaats daher nicht als unzul\u00e4ssig ablehnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Greece rejects asylum applications on the grounds that Turkey is a &#8222;safe third country&#8220;, but Turkey does not allow them to enter. From a question of mine it now emerges that the EU Commission classifies this procedure as contrary to European law. Although Turkey has not accepted readmissions since March 2020, Greece rejects the applications of Syrian, Afghan, Somali, Pakistani and Bangladeshi &hellip;<\/p>","protected":false},"author":2,"featured_media":2571,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,3],"tags":[],"class_list":["post-3205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-migration","category-politik","with-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kommission h\u00e4lt griechische Bearbeitung von Asylantr\u00e4gen f\u00fcr europarechtswidrig - Erik Marquardt<\/title>\n<meta name=\"description\" content=\"Griechenland lehnt Asylantr\u00e4ge mit der Begr\u00fcndung ab, die T\u00fcrkei sei ein &quot;sicherer Drittstaat&quot;, doch die T\u00fcrkei l\u00e4sst diese nicht einreisen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/erik-marquardt.eu\/en\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kommission h\u00e4lt griechische Bearbeitung von Asylantr\u00e4gen f\u00fcr europarechtswidrig\" \/>\n<meta property=\"og:description\" content=\"Griechenland lehnt Asylantr\u00e4ge mit der Begr\u00fcndung ab, die T\u00fcrkei sei ein &quot;sicherer Drittstaat&quot;, doch die T\u00fcrkei l\u00e4sst diese nicht einreisen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/erik-marquardt.eu\/en\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/\" \/>\n<meta property=\"og:site_name\" content=\"Erik Marquardt\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-25T18:26:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-26T18:42:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erik Marquardt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Kommission h\u00e4lt griechische Bearbeitung von Asylantr\u00e4gen f\u00fcr europarechtswidrig\" \/>\n<meta name=\"twitter:description\" content=\"Griechenland lehnt Asylantr\u00e4ge mit der Begr\u00fcndung ab, die T\u00fcrkei sei ein &quot;sicherer Drittstaat&quot;, doch die T\u00fcrkei l\u00e4sst diese nicht einreisen.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erik Marquardt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/\"},\"author\":{\"name\":\"Erik Marquardt\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\"},\"headline\":\"Kommission h\u00e4lt griechische Bearbeitung von Asylantr\u00e4gen f\u00fcr europarechtswidrig\",\"datePublished\":\"2022-01-25T18:26:00+00:00\",\"dateModified\":\"2022-01-26T18:42:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/\"},\"wordCount\":623,\"publisher\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\"},\"image\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/FG1A0284-scaled.jpg\",\"articleSection\":[\"Flucht und Migration\",\"Politik\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/\",\"name\":\"Kommission h\u00e4lt griechische Bearbeitung von Asylantr\u00e4gen f\u00fcr europarechtswidrig - Erik Marquardt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/FG1A0284-scaled.jpg\",\"datePublished\":\"2022-01-25T18:26:00+00:00\",\"dateModified\":\"2022-01-26T18:42:57+00:00\",\"description\":\"Griechenland lehnt Asylantr\u00e4ge mit der Begr\u00fcndung ab, die T\u00fcrkei sei ein \\\"sicherer Drittstaat\\\", doch die T\u00fcrkei l\u00e4sst diese nicht einreisen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/#primaryimage\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/FG1A0284-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/FG1A0284-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Johanna Feiler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/erik-marquardt.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kommission h\u00e4lt griechische Bearbeitung von Asylantr\u00e4gen f\u00fcr europarechtswidrig\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#website\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/\",\"name\":\"Erik Marquardt\",\"description\":\"Mitglied des Europ\u00e4ischen Parlaments \",\"publisher\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/erik-marquardt.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/#\\\/schema\\\/person\\\/ae6a90f9433e208a6be9ba844e6cff23\",\"name\":\"Erik Marquardt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\",\"url\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\",\"contentUrl\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\",\"width\":370,\"height\":123,\"caption\":\"Erik Marquardt\"},\"logo\":{\"@id\":\"https:\\\/\\\/erik-marquardt.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/erik-markquardt_combined-logo_same-size.svg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Commission deems Greek processing of asylum applications contrary to European law - Erik Marquardt","description":"Greece rejects asylum applications on the grounds that Turkey is a \"safe third country,\" but Turkey does not allow them to enter.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/erik-marquardt.eu\/en\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/","og_locale":"en_GB","og_type":"article","og_title":"Kommission h\u00e4lt griechische Bearbeitung von Asylantr\u00e4gen f\u00fcr europarechtswidrig","og_description":"Griechenland lehnt Asylantr\u00e4ge mit der Begr\u00fcndung ab, die T\u00fcrkei sei ein \"sicherer Drittstaat\", doch die T\u00fcrkei l\u00e4sst diese nicht einreisen.","og_url":"https:\/\/erik-marquardt.eu\/en\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/","og_site_name":"Erik Marquardt","article_published_time":"2022-01-25T18:26:00+00:00","article_modified_time":"2022-01-26T18:42:57+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg","type":"image\/jpeg"}],"author":"Erik Marquardt","twitter_card":"summary_large_image","twitter_title":"Kommission h\u00e4lt griechische Bearbeitung von Asylantr\u00e4gen f\u00fcr europarechtswidrig","twitter_description":"Griechenland lehnt Asylantr\u00e4ge mit der Begr\u00fcndung ab, die T\u00fcrkei sei ein \"sicherer Drittstaat\", doch die T\u00fcrkei l\u00e4sst diese nicht einreisen.","twitter_image":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg","twitter_misc":{"Written by":"Erik Marquardt","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/#article","isPartOf":{"@id":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/"},"author":{"name":"Erik Marquardt","@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23"},"headline":"Kommission h\u00e4lt griechische Bearbeitung von Asylantr\u00e4gen f\u00fcr europarechtswidrig","datePublished":"2022-01-25T18:26:00+00:00","dateModified":"2022-01-26T18:42:57+00:00","mainEntityOfPage":{"@id":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/"},"wordCount":623,"publisher":{"@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23"},"image":{"@id":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/#primaryimage"},"thumbnailUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg","articleSection":["Flucht und Migration","Politik"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/","url":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/","name":"Commission deems Greek processing of asylum applications contrary to European law - Erik Marquardt","isPartOf":{"@id":"https:\/\/erik-marquardt.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/#primaryimage"},"image":{"@id":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/#primaryimage"},"thumbnailUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg","datePublished":"2022-01-25T18:26:00+00:00","dateModified":"2022-01-26T18:42:57+00:00","description":"Greece rejects asylum applications on the grounds that Turkey is a \"safe third country,\" but Turkey does not allow them to enter.","breadcrumb":{"@id":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/#primaryimage","url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg","contentUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg","width":2560,"height":1707,"caption":"Johanna Feiler"},{"@type":"BreadcrumbList","@id":"https:\/\/erik-marquardt.eu\/kommission-haelt-griechische-bearbeitung-von-asylantraegen-fuer-europarechtswidrig\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/erik-marquardt.eu\/"},{"@type":"ListItem","position":2,"name":"Kommission h\u00e4lt griechische Bearbeitung von Asylantr\u00e4gen f\u00fcr europarechtswidrig"}]},{"@type":"WebSite","@id":"https:\/\/erik-marquardt.eu\/#website","url":"https:\/\/erik-marquardt.eu\/","name":"Erik Marquardt","description":"Member of the European Parliament","publisher":{"@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/erik-marquardt.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/erik-marquardt.eu\/#\/schema\/person\/ae6a90f9433e208a6be9ba844e6cff23","name":"Erik Marquardt","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg","url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg","contentUrl":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg","width":370,"height":123,"caption":"Erik Marquardt"},"logo":{"@id":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2025\/12\/erik-markquardt_combined-logo_same-size.svg"}}]}},"featured_image_src":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg","featured_image_src_square":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg","author_info":{"display_name":"Erik Marquardt","author_link":"https:\/\/erik-marquardt.eu\/en\/author\/erik\/"},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/erik-marquardt.eu\/wp-content\/uploads\/2021\/08\/FG1A0284-scaled.jpg","_links":{"self":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/posts\/3205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/comments?post=3205"}],"version-history":[{"count":0,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/posts\/3205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/media\/2571"}],"wp:attachment":[{"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/media?parent=3205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/categories?post=3205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/erik-marquardt.eu\/en\/wp-json\/wp\/v2\/tags?post=3205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}